{"id":1434,"count":12,"description":"","link":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/","name":"Bakterien","slug":"bakterien","taxonomy":"doc_category","parent":0,"meta":[],"acf":[],"doc_category_order":"6","thumbnail":null,"handbookthumbnail":null,"subcategories_count":0,"total_docs_count":12,"last_updated_time":"3. Juli 2026","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bakterien Archives - Aquaforest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bakterien Archives - Aquaforest\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquaforest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/wissensbasis-kategorien\\\/bakterien\\\/\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/wissensbasis-kategorien\\\/bakterien\\\/\",\"name\":\"Bakterien Archives - Aquaforest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/wissensbasis-kategorien\\\/bakterien\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/wissensbasis-kategorien\\\/bakterien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bakterien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/\",\"name\":\"Aquaforest\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#organization\",\"name\":\"Aquaforest\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logotyp-aquaforest.svg\",\"contentUrl\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logotyp-aquaforest.svg\",\"width\":170,\"height\":22,\"caption\":\"Aquaforest\"},\"image\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Aquaforest\\\/\",\"https:\\\/\\\/www.instagram.com\\\/aquaforest.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bakterien Archives - Aquaforest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/","og_locale":"de_DE","og_type":"article","og_title":"Bakterien Archives - Aquaforest","og_url":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/","og_site_name":"Aquaforest","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/","url":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/","name":"Bakterien Archives - Aquaforest","isPartOf":{"@id":"https:\/\/aquaforest.eu\/de\/#website"},"breadcrumb":{"@id":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/aquaforest.eu\/de\/wissensbasis-kategorien\/bakterien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquaforest.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Bakterien"}]},{"@type":"WebSite","@id":"https:\/\/aquaforest.eu\/de\/#website","url":"https:\/\/aquaforest.eu\/de\/","name":"Aquaforest","description":"","publisher":{"@id":"https:\/\/aquaforest.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquaforest.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aquaforest.eu\/de\/#organization","name":"Aquaforest","url":"https:\/\/aquaforest.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg","contentUrl":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg","width":170,"height":22,"caption":"Aquaforest"},"image":{"@id":"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Aquaforest\/","https:\/\/www.instagram.com\/aquaforest.eu\/"]}]}},"knowledge_base":["aquaforest-de","freshwater-de","seawater-de"],"knowledge_base_ids":[],"_links":{"self":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/doc_category\/1434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/doc_category"}],"about":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/taxonomies\/doc_category"}],"wp:post_type":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/docs?doc_category=1434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}