{"id":11202,"date":"2024-06-27T02:47:31","date_gmt":"2024-06-27T00:47:31","guid":{"rendered":"https:\/\/aquaforest.eu\/products\/unkategorisiert\/komponente-a\/"},"modified":"2026-04-30T14:30:16","modified_gmt":"2026-04-30T12:30:16","slug":"component-a","status":"publish","type":"product","link":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/","title":{"rendered":"Component A"},"content":{"rendered":"<h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"22\" data-lineheight=\"27.5px\"><strong><span style=\"color: #000000;\">Optimale Strontium- und Bariumwerte in Meerwasseraquarien<\/span><\/strong><\/h3>\n<p><span style=\"color: #000000;\">Komponente A wurde entwickelt, um kleinere M\u00e4ngel an Strontium und Barium in Meerwasseraquarien auszugleichen.<\/span><br \/>\n<span style=\"color: #000000;\">Die einzigartige Formel wurde auf der Grundlage des gleichen Strontium- und Bariumverh\u00e4ltnisses wie bei nat\u00fcrlichem Meerwasser entwickelt.<\/span><br \/>\n<span style=\"color: #000000;\">Absch\u00e4umer und Filtermedien neigen dazu, Spurenelemente aus dem Wasser geschlossener Aquariensysteme zu entfernen, was eine Erg\u00e4nzung mit Mikron\u00e4hrstoffen erforderlich macht.<\/span><\/p>\n<hr \/>\n<h3 class=\"fusion-responsive-typography-calculated\" data-fontsize=\"22\" data-lineheight=\"27.5px\"><strong><span style=\"color: #000000;\">Richtige Meerwassererg\u00e4nzung<\/span><\/strong><\/h3>\n<p><span style=\"color: #000000;\">Dank der perfekten Balance der Elemente erm\u00f6glicht Komponente A die Schaffung von Bedingungen, die fast identisch mit nat\u00fcrlichem Meerwasser sind.<\/span><br \/>\n<span style=\"color: #000000;\">Strontium unterst\u00fctzt die Bildung von Korallenskelettgewebe und verbessert die Aufnahme von Kalzium.<\/span><br \/>\n<span style=\"color: #000000;\">Es unterst\u00fctzt auch das Wachstum von Weichkorallen.<\/span><br \/>\n<span style=\"color: #000000;\">Die sichere Konzentration des Pr\u00e4parats minimiert die Gefahr einer \u00dcberdosierung von Mikron\u00e4hrstoffen, daher kann Komponente A auch von Aquaristik-Neulingen verwendet werden.<\/span><\/p>\n<hr \/>\n<h3><span style=\"color: #000000;\"><strong>Dosierung:<\/strong> <\/span><\/h3>\n<p><span style=\"color: #000000;\">In Aquarien mit gemischten Riffen 5 ml pro 100 l Wasser einmal pro Woche.<\/span><br \/>\n<span style=\"color: #000000;\">Die Dosis kann auch an den Kalziumverbrauch angepasst werden &#8211; 1 ml pro 20 ppm\/100 l Wasser.<\/span><br \/>\n<span style=\"color: #000000;\">In Aquarien, die mit der Balling-Methode betrieben werden &#8211; 20 ml\/1 l Calciuml\u00f6sung.<\/span><br \/>\n<span style=\"color: #000000;\">Wenn Sie die Komponenten A, B und C verwenden, sollten Sie zwischen den einzelnen Gaben einen Zeitabstand von 5 Minuten einhalten.<\/span><br \/>\n<span style=\"color: #000000;\">Mischen oder lagern Sie die Komponenten nicht in einem Beh\u00e4lter.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entwickelt, um kleinere Strontium- und Bariumm\u00e4ngel in Meerwasseraquarien auszugleichen.<\/p>\n","protected":false},"featured_media":11233,"template":"","meta":{"_acf_changed":false,"content-type":""},"product_brand":[],"product_cat":[1158],"product_tag":[966,1120,1417,1097],"class_list":["post-11202","product","type-product","status-publish","has-post-thumbnail","product_cat-wasseraufbereitung","product_tag-aquaforest-de","product_tag-meerwasser-aquarien","product_tag-variable-de","product_tag-wasserversorgung","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Component A - Aquaforest<\/title>\n<meta name=\"description\" content=\"Component A von Aquaforest: ein fortschrittliches Pr\u00e4parat zur pr\u00e4zisen Erh\u00f6hung des Magnesiumspiegels im Aquarium. Einzigartige Formel f\u00fcr gesunde Korallen und stabile Wasserbedingungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Component A - Aquaforest\" \/>\n<meta property=\"og:description\" content=\"Component A von Aquaforest: ein fortschrittliches Pr\u00e4parat zur pr\u00e4zisen Erh\u00f6hung des Magnesiumspiegels im Aquarium. Einzigartige Formel f\u00fcr gesunde Korallen und stabile Wasserbedingungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquaforest\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Aquaforest\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T12:30:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/06\/Component-A-250ml.png\" \/>\n\t<meta property=\"og:image:width\" content=\"391\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/\",\"name\":\"Component A - Aquaforest\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Component-A-250ml.png\",\"datePublished\":\"2024-06-27T00:47:31+00:00\",\"dateModified\":\"2026-04-30T12:30:16+00:00\",\"description\":\"Component A von Aquaforest: ein fortschrittliches Pr\u00e4parat zur pr\u00e4zisen Erh\u00f6hung des Magnesiumspiegels im Aquarium. Einzigartige Formel f\u00fcr gesunde Korallen und stabile Wasserbedingungen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Component-A-250ml.png\",\"contentUrl\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Component-A-250ml.png\",\"width\":391,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/seawater\\\/wasseraufbereitung\\\/component-a\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Component A\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/\",\"name\":\"Aquaforest\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#organization\",\"name\":\"Aquaforest\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logotyp-aquaforest.svg\",\"contentUrl\":\"https:\\\/\\\/aquaforest.eu\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logotyp-aquaforest.svg\",\"width\":170,\"height\":22,\"caption\":\"Aquaforest\"},\"image\":{\"@id\":\"https:\\\/\\\/aquaforest.eu\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Aquaforest\\\/\",\"https:\\\/\\\/www.instagram.com\\\/aquaforest.eu\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Component A - Aquaforest","description":"Component A von Aquaforest: ein fortschrittliches Pr\u00e4parat zur pr\u00e4zisen Erh\u00f6hung des Magnesiumspiegels im Aquarium. Einzigartige Formel f\u00fcr gesunde Korallen und stabile Wasserbedingungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/","og_locale":"de_DE","og_type":"article","og_title":"Component A - Aquaforest","og_description":"Component A von Aquaforest: ein fortschrittliches Pr\u00e4parat zur pr\u00e4zisen Erh\u00f6hung des Magnesiumspiegels im Aquarium. Einzigartige Formel f\u00fcr gesunde Korallen und stabile Wasserbedingungen.","og_url":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/","og_site_name":"Aquaforest","article_publisher":"https:\/\/www.facebook.com\/Aquaforest\/","article_modified_time":"2026-04-30T12:30:16+00:00","og_image":[{"width":391,"height":600,"url":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/06\/Component-A-250ml.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/","url":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/","name":"Component A - Aquaforest","isPartOf":{"@id":"https:\/\/aquaforest.eu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/#primaryimage"},"image":{"@id":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/#primaryimage"},"thumbnailUrl":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/06\/Component-A-250ml.png","datePublished":"2024-06-27T00:47:31+00:00","dateModified":"2026-04-30T12:30:16+00:00","description":"Component A von Aquaforest: ein fortschrittliches Pr\u00e4parat zur pr\u00e4zisen Erh\u00f6hung des Magnesiumspiegels im Aquarium. Einzigartige Formel f\u00fcr gesunde Korallen und stabile Wasserbedingungen.","breadcrumb":{"@id":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/#primaryimage","url":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/06\/Component-A-250ml.png","contentUrl":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/06\/Component-A-250ml.png","width":391,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/aquaforest.eu\/de\/produkte\/seawater\/wasseraufbereitung\/component-a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquaforest.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/aquaforest.eu\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"Component A"}]},{"@type":"WebSite","@id":"https:\/\/aquaforest.eu\/de\/#website","url":"https:\/\/aquaforest.eu\/de\/","name":"Aquaforest","description":"","publisher":{"@id":"https:\/\/aquaforest.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquaforest.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aquaforest.eu\/de\/#organization","name":"Aquaforest","url":"https:\/\/aquaforest.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg","contentUrl":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg","width":170,"height":22,"caption":"Aquaforest"},"image":{"@id":"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Aquaforest\/","https:\/\/www.instagram.com\/aquaforest.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product\/11202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product\/11202\/revisions"}],"predecessor-version":[{"id":31371,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product\/11202\/revisions\/31371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/media\/11233"}],"wp:attachment":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/media?parent=11202"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product_brand?post=11202"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product_cat?post=11202"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product_tag?post=11202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}