{"id":1144,"count":31,"description":"Entdecken Sie unsere breite Palette an Lab-Produkten, die entwickelt wurden, um Mikron\u00e4hrstoffdefizite in Ihrem Aquarium gezielt auszugleichen. In Kombination mit unseren ICP-Tests gew\u00e4hrleistet dieser Ansatz leuchtende Farben, Stabilit\u00e4t des \u00d6kosystems und allgemeine Gesundheit. Mit dieser umfassenden Methode k\u00f6nnen Sie sicher sein, dass Ihr Aquarium unter den bestm\u00f6glichen Bedingungen gedeiht.","link":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/","name":"Mikroelemente","slug":"mikroelemente","taxonomy":"product_cat","parent":1131,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mikroelemente Archives - Aquaforest<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mikroelemente Archives - Aquaforest\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie unsere breite Palette an Lab-Produkten, die entwickelt wurden, um Mikron\u00e4hrstoffdefizite in Ihrem Aquarium gezielt auszugleichen. In Kombination mit unseren ICP-Tests gew\u00e4hrleistet dieser Ansatz leuchtende Farben, Stabilit\u00e4t des \u00d6kosystems und allgemeine Gesundheit. Mit dieser umfassenden Methode k\u00f6nnen Sie sicher sein, dass Ihr Aquarium unter den bestm\u00f6glichen Bedingungen gedeiht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/\" \/>\n<meta property=\"og:site_name\" content=\"Aquaforest\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/\",\"url\":\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/\",\"name\":\"Mikroelemente Archives - Aquaforest\",\"isPartOf\":{\"@id\":\"https:\/\/aquaforest.eu\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/aquaforest.eu\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lab\",\"item\":\"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mikroelemente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/aquaforest.eu\/de\/#website\",\"url\":\"https:\/\/aquaforest.eu\/de\/\",\"name\":\"Aquaforest\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/aquaforest.eu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/aquaforest.eu\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/aquaforest.eu\/de\/#organization\",\"name\":\"Aquaforest\",\"url\":\"https:\/\/aquaforest.eu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg\",\"contentUrl\":\"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg\",\"width\":170,\"height\":22,\"caption\":\"Aquaforest\"},\"image\":{\"@id\":\"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Aquaforest\/\",\"https:\/\/www.instagram.com\/aquaforest.eu\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mikroelemente Archives - Aquaforest","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/","og_locale":"de_DE","og_type":"article","og_title":"Mikroelemente Archives - Aquaforest","og_description":"Entdecken Sie unsere breite Palette an Lab-Produkten, die entwickelt wurden, um Mikron\u00e4hrstoffdefizite in Ihrem Aquarium gezielt auszugleichen. In Kombination mit unseren ICP-Tests gew\u00e4hrleistet dieser Ansatz leuchtende Farben, Stabilit\u00e4t des \u00d6kosystems und allgemeine Gesundheit. Mit dieser umfassenden Methode k\u00f6nnen Sie sicher sein, dass Ihr Aquarium unter den bestm\u00f6glichen Bedingungen gedeiht.","og_url":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/","og_site_name":"Aquaforest","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/","url":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/","name":"Mikroelemente Archives - Aquaforest","isPartOf":{"@id":"https:\/\/aquaforest.eu\/de\/#website"},"breadcrumb":{"@id":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/mikroelemente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/aquaforest.eu\/de\/"},{"@type":"ListItem","position":2,"name":"Lab","item":"https:\/\/aquaforest.eu\/de\/produkte_\/lab\/"},{"@type":"ListItem","position":3,"name":"Mikroelemente"}]},{"@type":"WebSite","@id":"https:\/\/aquaforest.eu\/de\/#website","url":"https:\/\/aquaforest.eu\/de\/","name":"Aquaforest","description":"","publisher":{"@id":"https:\/\/aquaforest.eu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aquaforest.eu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/aquaforest.eu\/de\/#organization","name":"Aquaforest","url":"https:\/\/aquaforest.eu\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg","contentUrl":"https:\/\/aquaforest.eu\/wp-content\/uploads\/2024\/05\/logotyp-aquaforest.svg","width":170,"height":22,"caption":"Aquaforest"},"image":{"@id":"https:\/\/aquaforest.eu\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Aquaforest\/","https:\/\/www.instagram.com\/aquaforest.eu\/"]}]}},"_links":{"self":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product_cat\/1144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product_cat\/1131"}],"wp:post_type":[{"href":"https:\/\/aquaforest.eu\/de\/wp-json\/wp\/v2\/product?product_cat=1144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}